{"id":4520,"date":"2026-02-23T15:24:26","date_gmt":"2026-02-23T15:24:26","guid":{"rendered":"https:\/\/www2.scholastic.ca\/bookfairs\/?page_id=4520"},"modified":"2026-03-09T19:18:50","modified_gmt":"2026-03-09T19:18:50","slug":"book-a-discovery-call","status":"publish","type":"page","link":"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/","title":{"rendered":"Book a Discovery Call"},"content":{"rendered":"<div  class=\"container-fluid block_text\">\n\t<div class=\"bg-none mt-5 pb-5 container-fluid\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"col pb-2 text-center\">\n\t\t\t\t\t\t\t\t<h2 class=\"d-block mt-0\"><span>Let\u2019s Chat About Your School\u2019s Book Fair<\/span><\/h2>\n\t\t\t\t<p><span style=\"font-weight: 400\">A 15-minute discovery call is the easiest way to see if a Scholastic Book Fair is a good fit for <\/span><span style=\"font-weight: 400\">your school. You\u2019ll connect 1:1 with a Scholastic Consultant who can answer your questions, <\/span><span style=\"font-weight: 400\">explain how a Fair works, and help you get started with confidence.<\/span><\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<!-- ENGLISH RECAPTCHA -->\n<script src='https:\/\/www.google.com\/recaptcha\/api.js'><\/script>\n\n<!-- BUTTON STYLES -->\n<style>\n::-moz-selection{color: #e81111;background: rgba(216, 36, 51, 0.1);}::selection{color: #e81111;background:rgba(216, 36, 51, 0.1);}.form-check-input:checked{background-color: #e81111;border-color: #e81111;}.help-block{display: block;margin-top: 5px;margin-bottom: 10px;color: #737373;}.b3-pb-3{padding-bottom:1rem!important;}input:invalid{background-color:rgba(216, 36, 51, 0.1);}.btn-main{color:#fff;background-color:#e81111;border-color:#e81111}.btn-main.active,.btn-main:active,.btn-main:focus,.btn-main:hover,.open .dropdown-toggle.btn-main{color:#fff;background-color:#b10c1a;border-color:#e81111}.btn-main.active,.btn-main:active,.open .dropdown-toggle.btn-main{background-image:none}.btn-main.disabled,.btn-main.disabled.active,.btn-main.disabled:active,.btn-main.disabled:focus,.btn-main.disabled:hover,.btn-main[disabled],.btn-main[disabled].active,.btn-main[disabled]:active,.btn-main[disabled]:focus,.btn-main[disabled]:hover,fieldset[disabled] .btn-main,fieldset[disabled] .btn-main.active,fieldset[disabled] .btn-main:active,fieldset[disabled] .btn-main:focus,fieldset[disabled] .btn-main:hover{background-color:#e81111;border-color:#e81111}.btn-main .badge{color:#e81111;background-color:#fff}.btn-sub{color:#777;background-color:#efefef;border-color:#efefef}.btn-sub.active,.btn-sub:active,.btn-sub:focus,.btn-sub:hover,.open .dropdown-toggle.btn-sub{color:#777;background-color:#dedbdb;border-color:#efefef}.btn-sub.active,.btn-sub:active,.open .dropdown-toggle.btn-sub{background-image:none}.btn-sub.disabled,.btn-sub.disabled.active,.btn-sub.disabled:active,.btn-sub.disabled:focus,.btn-sub.disabled:hover,.btn-sub[disabled],.btn-sub[disabled].active,.btn-sub[disabled]:active,.btn-sub[disabled]:focus,.btn-sub[disabled]:hover,fieldset[disabled] .btn-sub,fieldset[disabled] .btn-sub.active,fieldset[disabled] .btn-sub:active,fieldset[disabled] .btn-sub:focus,fieldset[disabled] .btn-sub:hover{background-color:#efefef;border-color:#efefef}.btn-sub .badge{color:#efefef;background-color:#777}.step-block{display:none}.step-block.active{display:block}label.mandatory:after{content:\"\\00a0*\";color:#e81111;}\n<\/style>\n\n<div class=\"container\">\n\t<div class=\"row\">\n\t\t<div class=\"col\">\n\t\t\t<form id=\"discoverycallform\" class=\"form col-12\" method=\"post\" action=\"https:\/\/www2.scholastic.ca\/bookfairs\/wp-content\/themes\/scholastic-ca-bookfairs-wp\/blocks\/discoverycallform\/inc\/process.discoverycallform.php\">\n\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"mb-3 col-md-4\">\n\t\t\t\t\t\t<label for=\"firstname\" class=\"form-label mandatory\">First Name<\/label>\n\t\t\t\t\t\t<input type=\"text\" class=\"form-control\" id=\"firstname\" name=\"firstname\" placeholder=\"First Name\" required  aria-label=\"First Name Input\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mb-3 col-md-4\">\n\t\t\t\t\t\t<label for=\"lastname\" class=\"form-label mandatory\">Last Name<\/label>\n\t\t\t\t\t\t<input type=\"text\" class=\"form-control\" id=\"lastname\" name=\"lastname\" placeholder=\"Last Name\" required  aria-label=\"Last Name Input\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mb-3 col-md-4\">\n\t\t\t\t\t\t<label for=\"email\" class=\"form-label mandatory\">Email Address<\/label>\n\t\t\t\t\t\t<input type=\"email\" class=\"form-control\" id=\"email\" name=\"email\" placeholder=\"Email Address\" required  aria-label=\"Email Address Input\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mb-3 col-md-6\">\n\t\t\t\t\t\t<label for=\"position\" class=\"form-label mandatory\">Position<\/label>\n\t\t\t\t\t\t<select class=\"form-control\" aria-label=\"Position Select Input\" id=\"position\" name=\"position\" required>\n\t\t\t\t\t\t\t<option selected disabled>&#8212; Please Select &#8212;<\/option>\n\t\t\t\t\t\t\t<option value=\"Teacher\" >Teacher<\/option>\n\t\t\t\t\t\t\t<option value=\"Librarian\" >Librarian<\/option>\n\t\t\t\t\t\t\t<option value=\"Teacher-Librarian\" >Teacher-Librarian<\/option>\n\t\t\t\t\t\t\t<option value=\"Library Technician\" >Library Technician<\/option>\n\t\t\t\t\t\t\t<option value=\"PTA\/PTO\/PAC\" >PTA\/PTO\/PAC<\/option>\n\t\t\t\t\t\t\t<option value=\"Parent Volunteer\" >Parent Volunteer<\/option>\n\t\t\t\t\t\t\t<option value=\"Other\" >Other<\/option>\n\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mb-3 col-md-6\">\n\t\t\t\t\t\t<label for=\"nameofschool\" class=\"form-label mandatory\">School Name<\/label>\n\t\t\t\t\t\t<input type=\"text\" class=\"form-control\" id=\"nameofschool\" name=\"nameofschool\" placeholder=\"School Name\" required  aria-label=\"School Name Input\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mb-3 col-md-6\">\n\t\t\t\t\t\t<label for=\"school_address\" class=\"form-label mandatory\">School Address<\/label>\n\t\t\t\t\t\t<input type=\"text\" class=\"form-control\" id=\"school_address\" name=\"school_address\" placeholder=\"School Address\" required  aria-label=\"School Address Input\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<!-- SELECT MENU BLOCK -->\n\t\t\t\t\t<div class=\"mb-3 col-md-6\">\n\t\t\t\t\t\t<label for=\"school_province\" class=\"form-label mandatory\">School Province<\/label>\n\t\t\t\t\t\t<select class=\"form-control\" aria-label=\"School Province Select Input\" id=\"school_province\" name=\"school_province\" required>\n\t\t\t\t\t\t\t<option selected disabled>&#8212; Please Select &#8212;<\/option>\n\t\t\t\t\t\t\t<option value=\"AB\" >Alberta<\/option>\n\t\t\t\t\t\t\t<option value=\"BC\" >British Columbia<\/option>\n\t\t\t\t\t\t\t<option value=\"MB\" >Manitoba<\/option>\n\t\t\t\t\t\t\t<option value=\"NB\" >New Brunswick<\/option>\n\t\t\t\t\t\t\t<option value=\"NL\" >Newfoundland and Labrador<\/option>\n\t\t\t\t\t\t\t<option value=\"NS\" >Nova Scotia<\/option>\n\t\t\t\t\t\t\t<option value=\"ON\" >Ontario<\/option>\n\t\t\t\t\t\t\t<option value=\"PE\" >Prince Edward Island<\/option>\n\t\t\t\t\t\t\t<option value=\"QC\" >Quebec<\/option>\n\t\t\t\t\t\t\t<option value=\"SK\" >Saskatchewan<\/option>\n\t\t\t\t\t\t\t<option value=\"NT\" >Northwest Territories<\/option>\n\t\t\t\t\t\t\t<option value=\"NU\" >Nunavut<\/option>\n\t\t\t\t\t\t\t<option value=\"YT\" >Yukon<\/option>\n\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mb-3 col-md-6\">\n\t\t\t\t\t\t<label for=\"phone\" class=\"form-label mandatory\">Phone Number<\/label>\n\t\t\t\t\t\t<input type=\"tel\" class=\"form-control\" id=\"phone\" name=\"phone\" placeholder=\"\"  aria-label=\"Phone Number Input\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"row mt-3\">\n\t\t\t\t\t<div class=\"mb-3 col-md-6\">\n\t\t\t\t\t\t<fieldset>\n\t\t\t\t\t\t\t<legend>What time of day works best for your 15-minute call?<\/legend>\n\t\t\t\t\t\t\t<div class=\"form-check form-check-inline\">\n\t\t\t\t\t\t\t\t<input class=\"form-check-input\" type=\"checkbox\" id=\"discoverycall_besttime_morning\" name=\"discoverycall_besttime_morning\" value=\"Morning (9am - 11:30am)\" aria-label=\"Morning (9am - 11:30am)\" >\n\t\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"discoverycall_besttime_morning\">Morning (9am &#8211; 11:30am)<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"form-check form-check-inline\">\n\t\t\t\t\t\t\t\t<input class=\"form-check-input\" type=\"checkbox\" id=\"discoverycall_besttime_afternoon\" name=\"discoverycall_besttime_afternoon\" value=\"Afternoon (12pm - 5pm)\" aria-label=\"Afternoon (12pm - 5pm)\" >\n\t\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"discoverycall_besttime_afternoon\">Afternoon (12pm &#8211; 5pm)<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/fieldset>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mb-3 col-md-6\">\n\t\t\t\t\t\t<fieldset>\n\t\t\t\t\t\t\t<legend>Which day of the week works best for you?<\/legend>\n\t\t\t\t\t\t\t<div class=\"form-check form-check-inline\">\n\t\t\t\t\t\t\t\t<input class=\"form-check-input\" type=\"checkbox\" id=\"discoverycall_bestday_monday\" name=\"discoverycall_bestday_monday\" value=\"Monday\" aria-label=\"Monday\" >\n\t\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"discoverycall_bestday_monday\">Monday<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"form-check form-check-inline\">\n\t\t\t\t\t\t\t\t<input class=\"form-check-input\" type=\"checkbox\" id=\"discoverycall_bestday_tuesday\" name=\"discoverycall_bestday_tuesday\" value=\"Tuesday\" aria-label=\"Tuesday\" >\n\t\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"discoverycall_bestday_tuesday\">Tuesday<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"form-check form-check-inline\">\n\t\t\t\t\t\t\t\t<input class=\"form-check-input\" type=\"checkbox\" id=\"discoverycall_bestday_wednesday\" name=\"discoverycall_bestday_wednesday\" value=\"Wednesday\" aria-label=\"Wednesday\" >\n\t\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"discoverycall_bestday_wednesday\">Wednesday<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"form-check form-check-inline\">\n\t\t\t\t\t\t\t\t<input class=\"form-check-input\" type=\"checkbox\" id=\"discoverycall_bestday_thursday\" name=\"discoverycall_bestday_thursday\" value=\"Thursday\" aria-label=\"Thursday\" >\n\t\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"discoverycall_bestday_thursday\">Thursday<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"form-check form-check-inline\">\n\t\t\t\t\t\t\t\t<input class=\"form-check-input\" type=\"checkbox\" id=\"discoverycall_bestday_friday\" name=\"discoverycall_bestday_friday\" value=\"Friday\" aria-label=\"Friday\" >\n\t\t\t\t\t\t\t\t<label class=\"form-check-label\" for=\"discoverycall_bestday_friday\">Friday<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/fieldset>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"mt-3 row\">\n\t\t\t\t\t<!-- GOOGLE RECAPTCHA BLOCK -->\n\t\t\t\t\t<div class=\"col-md-12 mb-3\">\n\t\t\t\t\t\t<div class=\"reCaptcha\"><div class=\"g-recaptcha\" data-sitekey=\"6LfwdWggAAAAADOXNAnlNgcwC4jSgzalWEN8LDAD\"><\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"mb-3 col-md-6\">\n\t\t\t\t\t\t<input type=\"hidden\" name=\"thank_you\" value=\"https:\/\/www2.scholastic.ca\/bookfairs\/thank-you-discovery-call\/\">\n\t\t\t\t\t\t<input type=\"hidden\" name=\"email_to\" value=\"\">\n            \t\t\t<input type=\"hidden\" name=\"csrf_token\" value=\"8aa8117668e8ebe11fa75102c67ce203\">\n\t\t\t\t\t\t<button type=\"submit\" class=\"btn btn-primary rounded-pill\">Submit request<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t<\/div>\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":true,"footnotes":""},"class_list":["post-4520","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Book a Discovery Call | Scholastic Canada Book Fairs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Book a Discovery Call | Scholastic Canada Book Fairs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/\" \/>\n<meta property=\"og:site_name\" content=\"Scholastic Canada Book Fairs\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T19:18:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/\",\"url\":\"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/\",\"name\":\"Book a Discovery Call | Scholastic Canada Book Fairs\",\"isPartOf\":{\"@id\":\"https:\/\/www2.scholastic.ca\/bookfairs\/#website\"},\"datePublished\":\"2026-02-23T15:24:26+00:00\",\"dateModified\":\"2026-03-09T19:18:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www2.scholastic.ca\/bookfairs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Book a Discovery Call\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www2.scholastic.ca\/bookfairs\/#website\",\"url\":\"https:\/\/www2.scholastic.ca\/bookfairs\/\",\"name\":\"Scholastic Canada Book Fairs\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www2.scholastic.ca\/bookfairs\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Book a Discovery Call | Scholastic Canada Book Fairs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/","og_locale":"en_US","og_type":"article","og_title":"Book a Discovery Call | Scholastic Canada Book Fairs","og_url":"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/","og_site_name":"Scholastic Canada Book Fairs","article_modified_time":"2026-03-09T19:18:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/","url":"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/","name":"Book a Discovery Call | Scholastic Canada Book Fairs","isPartOf":{"@id":"https:\/\/www2.scholastic.ca\/bookfairs\/#website"},"datePublished":"2026-02-23T15:24:26+00:00","dateModified":"2026-03-09T19:18:50+00:00","breadcrumb":{"@id":"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www2.scholastic.ca\/bookfairs\/book-a-discovery-call\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www2.scholastic.ca\/bookfairs\/"},{"@type":"ListItem","position":2,"name":"Book a Discovery Call"}]},{"@type":"WebSite","@id":"https:\/\/www2.scholastic.ca\/bookfairs\/#website","url":"https:\/\/www2.scholastic.ca\/bookfairs\/","name":"Scholastic Canada Book Fairs","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www2.scholastic.ca\/bookfairs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www2.scholastic.ca\/bookfairs\/wp-json\/wp\/v2\/pages\/4520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.scholastic.ca\/bookfairs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www2.scholastic.ca\/bookfairs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www2.scholastic.ca\/bookfairs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.scholastic.ca\/bookfairs\/wp-json\/wp\/v2\/comments?post=4520"}],"version-history":[{"count":0,"href":"https:\/\/www2.scholastic.ca\/bookfairs\/wp-json\/wp\/v2\/pages\/4520\/revisions"}],"wp:attachment":[{"href":"https:\/\/www2.scholastic.ca\/bookfairs\/wp-json\/wp\/v2\/media?parent=4520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}